{"id":5,"count":10,"description":"","link":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/","name":"Immobilie","slug":"immobilie","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.6 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Immobilie Archive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immobilie Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/\" \/>\n<meta property=\"og:site_name\" content=\"Vergleich Bausparen &amp; Baufinanzierung\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Bausparen24\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/category\\\/immobilie\\\/\",\"url\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/category\\\/immobilie\\\/\",\"name\":\"Immobilie Archive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/category\\\/immobilie\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/category\\\/immobilie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/\",\"name\":\"Vergleich Bausparen &amp; Baufinanzierung\",\"description\":\"Bausparvertr\u00e4ge f\u00fcr Sparrer oder Finanzierer einfach online vergleichen - Vergleich Baufinanzierung unverbindlich anfordern und \u00fcber 450 Banken vergleichen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/#organization\",\"name\":\"Vergleich Bausparen & Baufinanzierung\",\"url\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/logo-1.png\",\"width\":362,\"height\":53,\"caption\":\"Vergleich Bausparen & Baufinanzierung\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vergleich-bausparen.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vergleichbausparen\\\/\",\"https:\\\/\\\/x.com\\\/Bausparen24\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Immobilie Archive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/","og_locale":"de_DE","og_type":"article","og_title":"Immobilie Archive","og_url":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/","og_site_name":"Vergleich Bausparen &amp; Baufinanzierung","twitter_card":"summary_large_image","twitter_site":"@Bausparen24","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/","url":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/","name":"Immobilie Archive","isPartOf":{"@id":"https:\/\/www.vergleich-bausparen.de\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vergleich-bausparen.de\/de\/category\/immobilie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vergleich-bausparen.de\/de\/"},{"@type":"ListItem","position":2,"name":"Immobilie"}]},{"@type":"WebSite","@id":"https:\/\/www.vergleich-bausparen.de\/de\/#website","url":"https:\/\/www.vergleich-bausparen.de\/de\/","name":"Vergleich Bausparen &amp; Baufinanzierung","description":"Bausparvertr\u00e4ge f\u00fcr Sparrer oder Finanzierer einfach online vergleichen - Vergleich Baufinanzierung unverbindlich anfordern und \u00fcber 450 Banken vergleichen.","publisher":{"@id":"https:\/\/www.vergleich-bausparen.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vergleich-bausparen.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vergleich-bausparen.de\/de\/#organization","name":"Vergleich Bausparen & Baufinanzierung","url":"https:\/\/www.vergleich-bausparen.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vergleich-bausparen.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.vergleich-bausparen.de\/de\/wp-content\/uploads\/2016\/02\/logo-1.png","contentUrl":"https:\/\/www.vergleich-bausparen.de\/de\/wp-content\/uploads\/2016\/02\/logo-1.png","width":362,"height":53,"caption":"Vergleich Bausparen & Baufinanzierung"},"image":{"@id":"https:\/\/www.vergleich-bausparen.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vergleichbausparen\/","https:\/\/x.com\/Bausparen24"]}]}},"_links":{"self":[{"href":"https:\/\/www.vergleich-bausparen.de\/de\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vergleich-bausparen.de\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.vergleich-bausparen.de\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.vergleich-bausparen.de\/de\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}